{"id":2741,"date":"2024-10-17T11:38:48","date_gmt":"2024-10-17T09:38:48","guid":{"rendered":"https:\/\/www.hotelvareseroma.com\/staff\/"},"modified":"2024-10-21T13:44:59","modified_gmt":"2024-10-21T11:44:59","slug":"personnel","status":"publish","type":"page","link":"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/","title":{"rendered":"Personnel"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2741\" class=\"elementor elementor-2741\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e85393 e-flex e-con-boxed e-con e-parent\" data-id=\"6e85393\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f78f4d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9f78f4d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Personnel<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-688a5b09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"688a5b09\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42e784c3\" data-id=\"42e784c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6854f71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6854f71\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1900c76\" data-id=\"1900c76\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f17705 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5f17705\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre personnel<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-183c94d gallery-spacing-custom hover-galleria staff-gallery elementor-widget elementor-widget-image-gallery\" data-id=\"183c94d\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-2741 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYzMCwidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDAxLmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001-768x1024.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001-225x300.jpg 225w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001-1152x1536.jpg 1152w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001-38x50.jpg 38w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001-600x800.jpg 600w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001.jpg 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYzMSwidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDAyLmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-002.jpg'><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-002.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-002.jpg 1024w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-002-300x225.jpg 300w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-002-768x576.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-002-50x38.jpg 50w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-002-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYzMiwidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDAzLmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-003.jpg'><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-003.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-003.jpg 1024w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-003-300x225.jpg 300w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-003-768x576.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-003-50x38.jpg 50w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-003-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYzMywidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDA0LmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-004.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-004.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-004.jpg 1024w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-004-300x225.jpg 300w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-004-768x576.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-004-50x38.jpg 50w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-004-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYzNCwidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDA1LmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-005.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-005.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-005.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-005-225x300.jpg 225w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-005-38x50.jpg 38w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-005-600x800.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYzNSwidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDA2LmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-006.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-006-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-006-1024x768.jpg 1024w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-006-300x225.jpg 300w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-006-768x576.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-006-1536x1152.jpg 1536w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-006-50x38.jpg 50w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-006-600x450.jpg 600w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-006.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYzNiwidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDA3LmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-007.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-007-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-007-768x1024.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-007-225x300.jpg 225w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-007-1152x1536.jpg 1152w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-007-38x50.jpg 38w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-007-600x800.jpg 600w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-007.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYzNywidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDA4LmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-008.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-008-1024x768.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-008-1024x768.jpg 1024w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-008-300x225.jpg 300w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-008-768x576.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-008-1536x1152.jpg 1536w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-008-50x38.jpg 50w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-008-600x450.jpg 600w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-008.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYzOCwidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDA5LmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-009.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-009.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-009.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-009-225x300.jpg 225w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-009-38x50.jpg 38w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-009-600x800.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjYzOSwidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDEwLmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-010.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-010.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-010.jpg 1024w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-010-300x225.jpg 300w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-010-768x576.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-010-50x38.jpg 50w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-010-600x450.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjY0MCwidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDExLmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-011.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-011.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-011.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-011-225x300.jpg 225w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-011-38x50.jpg 38w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-011-600x800.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"183c94d\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjY0MSwidXJsIjoiaHR0cHM6XC9cL3d3dy5ob3RlbHZhcmVzZXJvbWEuY29tXC93cC1jbnRudFwvdXBsZHNcLzIwMjRcLzEwXC9ob3RlbC12YXJlc2Utc3RhZmYtMDEyLmpwZyIsInNsaWRlc2hvdyI6IjE4M2M5NGQifQ%3D%3D\" href='https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-012.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"852\" src=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-012-1024x852.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-012-1024x852.jpg 1024w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-012-300x250.jpg 300w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-012-768x639.jpg 768w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-012-1536x1278.jpg 1536w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-012-50x42.jpg 50w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-012-600x499.jpg 600w, https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-012.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Personnel Notre personnel<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-2741","page","type-page","status-publish","hentry","blog-item column column-3 no-thumb clearfix"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le personnel de l&#039;H\u00f4tel Varese *** S - Rome<\/title>\n<meta name=\"description\" content=\"L&#039;hospitalit\u00e9 n&#039;est pas un m\u00e9tier, mais un style de vie ! Le Directeur et tout le personnel vous souhaitent la bienvenue \u00e0 l&#039;H\u00f4tel Varese\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le personnel de l&#039;H\u00f4tel Varese *** S - Rome\" \/>\n<meta property=\"og:description\" content=\"L&#039;hospitalit\u00e9 n&#039;est pas un m\u00e9tier, mais un style de vie ! Le Directeur et tout le personnel vous souhaitent la bienvenue \u00e0 l&#039;H\u00f4tel Varese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Varese\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-21T11:44:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001-768x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/personnel\\\/\",\"url\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/personnel\\\/\",\"name\":\"Le personnel de l'H\u00f4tel Varese *** S - Rome\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/personnel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/personnel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/wp-cntnt\\\/uplds\\\/2024\\\/10\\\/hotel-varese-staff-001-768x1024.jpg\",\"datePublished\":\"2024-10-17T09:38:48+00:00\",\"dateModified\":\"2024-10-21T11:44:59+00:00\",\"description\":\"L'hospitalit\u00e9 n'est pas un m\u00e9tier, mais un style de vie ! Le Directeur et tout le personnel vous souhaitent la bienvenue \u00e0 l'H\u00f4tel Varese\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/personnel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/personnel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/personnel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/wp-cntnt\\\/uplds\\\/2024\\\/10\\\/hotel-varese-staff-001-768x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/wp-cntnt\\\/uplds\\\/2024\\\/10\\\/hotel-varese-staff-001-768x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/personnel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Personnel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/\",\"name\":\"Hotel Varese\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hotelvareseroma.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le personnel de l'H\u00f4tel Varese *** S - Rome","description":"L'hospitalit\u00e9 n'est pas un m\u00e9tier, mais un style de vie ! Le Directeur et tout le personnel vous souhaitent la bienvenue \u00e0 l'H\u00f4tel Varese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/","og_locale":"fr_FR","og_type":"article","og_title":"Le personnel de l'H\u00f4tel Varese *** S - Rome","og_description":"L'hospitalit\u00e9 n'est pas un m\u00e9tier, mais un style de vie ! Le Directeur et tout le personnel vous souhaitent la bienvenue \u00e0 l'H\u00f4tel Varese","og_url":"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/","og_site_name":"Hotel Varese","article_modified_time":"2024-10-21T11:44:59+00:00","og_image":[{"url":"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001-768x1024.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/","url":"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/","name":"Le personnel de l'H\u00f4tel Varese *** S - Rome","isPartOf":{"@id":"https:\/\/www.hotelvareseroma.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/#primaryimage"},"image":{"@id":"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001-768x1024.jpg","datePublished":"2024-10-17T09:38:48+00:00","dateModified":"2024-10-21T11:44:59+00:00","description":"L'hospitalit\u00e9 n'est pas un m\u00e9tier, mais un style de vie ! Le Directeur et tout le personnel vous souhaitent la bienvenue \u00e0 l'H\u00f4tel Varese","breadcrumb":{"@id":"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hotelvareseroma.com\/fr\/personnel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/#primaryimage","url":"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001-768x1024.jpg","contentUrl":"https:\/\/www.hotelvareseroma.com\/wp-cntnt\/uplds\/2024\/10\/hotel-varese-staff-001-768x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hotelvareseroma.com\/fr\/personnel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hotelvareseroma.com\/es\/"},{"@type":"ListItem","position":2,"name":"Personnel"}]},{"@type":"WebSite","@id":"https:\/\/www.hotelvareseroma.com\/fr\/#website","url":"https:\/\/www.hotelvareseroma.com\/fr\/","name":"Hotel Varese","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hotelvareseroma.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.hotelvareseroma.com\/fr\/wp-json\/wp\/v2\/pages\/2741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelvareseroma.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelvareseroma.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelvareseroma.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelvareseroma.com\/fr\/wp-json\/wp\/v2\/comments?post=2741"}],"version-history":[{"count":4,"href":"https:\/\/www.hotelvareseroma.com\/fr\/wp-json\/wp\/v2\/pages\/2741\/revisions"}],"predecessor-version":[{"id":2750,"href":"https:\/\/www.hotelvareseroma.com\/fr\/wp-json\/wp\/v2\/pages\/2741\/revisions\/2750"}],"wp:attachment":[{"href":"https:\/\/www.hotelvareseroma.com\/fr\/wp-json\/wp\/v2\/media?parent=2741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}